{"id":1135,"date":"2023-09-11T18:27:03","date_gmt":"2023-09-11T16:27:03","guid":{"rendered":"https:\/\/www.tophosteleriaprojects.com\/?page_id=1135"},"modified":"2023-10-16T17:47:14","modified_gmt":"2023-10-16T15:47:14","slug":"armarios-refrigerados","status":"publish","type":"page","link":"https:\/\/www.tophosteleriaprojects.com\/es\/maquinaria-frio\/armarios-refrigerados\/","title":{"rendered":"Armarios y expositores"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1135\" class=\"elementor elementor-1135\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3aa0680 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"3aa0680\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e3789e\" data-id=\"7e3789e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45564b1 elementor-pagination-position-outside elementor--h-position-center elementor--v-position-middle elementor-widget elementor-widget-slides\" data-id=\"45564b1\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.16.0 - 20-09-2023 *\/\n.elementor-slides .swiper-slide-bg{background-size:cover;background-position:50%;background-repeat:no-repeat;min-width:100%;min-height:100%}.elementor-slides .swiper-slide-inner{background-repeat:no-repeat;background-position:50%;position:absolute;top:0;left:0;bottom:0;right:0;padding:50px;margin:auto}.elementor-slides .swiper-slide-inner,.elementor-slides .swiper-slide-inner:hover{color:#fff;display:flex}.elementor-slides .swiper-slide-inner .elementor-background-overlay{position:absolute;z-index:0;top:0;bottom:0;left:0;right:0}.elementor-slides .swiper-slide-inner .elementor-slide-content{position:relative;z-index:1;width:100%}.elementor-slides .swiper-slide-inner .elementor-slide-heading{font-size:35px;font-weight:700;line-height:1}.elementor-slides .swiper-slide-inner .elementor-slide-description{font-size:17px;line-height:1.4}.elementor-slides .swiper-slide-inner .elementor-slide-description:not(:last-child),.elementor-slides .swiper-slide-inner .elementor-slide-heading:not(:last-child){margin-bottom:30px}.elementor-slides .swiper-slide-inner .elementor-slide-button{border:2px solid #fff;color:#fff;background:transparent;display:inline-block}.elementor-slides .swiper-slide-inner .elementor-slide-button,.elementor-slides .swiper-slide-inner .elementor-slide-button:hover{background:transparent;color:inherit;text-decoration:none}.elementor--v-position-top .swiper-slide-inner{align-items:flex-start}.elementor--v-position-bottom .swiper-slide-inner{align-items:flex-end}.elementor--v-position-middle .swiper-slide-inner{align-items:center}.elementor--h-position-left .swiper-slide-inner{justify-content:flex-start}.elementor--h-position-right .swiper-slide-inner{justify-content:flex-end}.elementor--h-position-center .swiper-slide-inner{justify-content:center}body.rtl .elementor-widget-slides .elementor-swiper-button-next{left:10px;right:auto}body.rtl .elementor-widget-slides .elementor-swiper-button-prev{right:10px;left:auto}.elementor-slides-wrapper div:not(.swiper-slide)>.swiper-slide-inner{display:none}@media (max-width:767px){.elementor-slides .swiper-slide-inner{padding:30px}.elementor-slides .swiper-slide-inner .elementor-slide-heading{font-size:23px;line-height:1;margin-bottom:15px}.elementor-slides .swiper-slide-inner .elementor-slide-description{font-size:13px;line-height:1.4;margin-bottom:15px}}<\/style>\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-04af710 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-235e0e7 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-326f681 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-873a2fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"873a2fd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-634f1b2\" data-id=\"634f1b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94fef9b elementor-widget elementor-widget-heading\" data-id=\"94fef9b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">ARMARIOS Y EXPOSITORES REFRIGERADOS<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f4a05f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f4a05f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5168f99\" data-id=\"5168f99\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54df69f elementor-widget elementor-widget-text-editor\" data-id=\"54df69f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Para acertar en la elecci\u00f3n de un <a href=\"https:\/\/www.tophosteleria.com\/es\/22-armarios-refrigerados\" target=\"_blank\" rel=\"noopener\"><strong>armario refrigerado <\/strong><\/a>o un <strong><a href=\"https:\/\/www.tophosteleria.com\/es\/54-expositores-verticales\" target=\"_blank\" rel=\"noopener\">expositor<\/a><\/strong>, primero de todo piensa para qu\u00e9 lo necesitas, en base a eso, podr\u00e1s eliminar muchas opciones que no encajar\u00edan en tus necesidades. Debes tener en cuenta el rango de temperatura (conservaci\u00f3n o congelaci\u00f3n), tipo de bandejas; n\u00famero de bandejas y gu\u00edas y qu\u00e9 dotaci\u00f3n incluye; y el acabado exterior, si es para exposici\u00f3n ser\u00e1 interesante que tenga puertas de cristal, y si es para almacenamiento en la cocina, puede ser acabado en blanco o en inox. Tambi\u00e9n hay que ver a qu\u00e9 vas a dedicar el armario refrigerado, porque los encontramos espec\u00edficos para distintas funcionalidades, como farmacia, fermentaci\u00f3n controlada, maduraci\u00f3n de carne o secaderos de embutidos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a7b6d4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5a7b6d4\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e2b7adf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e2b7adf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8bf354d imatge-fons\" data-id=\"8bf354d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-64ba27a\" data-id=\"64ba27a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97f34ec elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"97f34ec\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>La <strong>temperatura de trabajo<\/strong> puede ser positiva o negativa, es decir, para <strong>conservaci\u00f3n<\/strong> \u2013nevera- o <strong>congelaci\u00f3n<\/strong> \u2013congelador-. Hay varios rangos, pero en general los dividimos entre conservaci\u00f3n -2\u00baC +6\u00baC o +8\u00baC, conservaci\u00f3n para <strong>pescado<\/strong>, que no supera los 0\u00baC, y congelaci\u00f3n de -18\u00baC a -22\u00baC, y conservaci\u00f3n espec\u00edfica para <strong>helado artesanal<\/strong>, con una temperatura m\u00e1s alta, entre los -14\u00baC y los -16\u00baC. El material exterior puede ser en<strong> blanco<\/strong> o en <strong>acero inoxidable<\/strong>. Los m\u00e1s robustos tienen interior y exterior en inox, y son mucho m\u00e1s pesados pero mucho m\u00e1s resistentes. Para la exposici\u00f3n, est\u00e1n disponibles con <strong>puerta de cristal<\/strong>, normalmente los de conservaci\u00f3n tienen doble cristal, y los de congelaci\u00f3n triple cristal y marcos calefactados para evitar la acumulaci\u00f3n de hielo. Tambi\u00e9n debes valorar el <strong>espesor<\/strong> de las paredes: a m\u00e1s grueso, mejor aislado; el<strong> tipo de refrigeraci\u00f3n<\/strong>, que puede ser est\u00e1tica o ventilada; la clase clim\u00e1tica si te la indican; y si dispone de desescarche autom\u00e1tico o no. Pueden tener puertas enteras o medias puertas, que resultan muy \u00fatiles para no perder temperatura, y seg\u00fan la serie tendr\u00e1n las <strong>bandejas<\/strong> de una <strong>medida<\/strong> o de otra. En general, se diferencian por la gama <strong>snack<\/strong>, que cada fabricante tiene sus medidas propias; la medida <strong>GN 1\/1<\/strong>, que puede ser para una o para dos bandejas por gu\u00eda; y por \u00faltimo los adaptados a la medida de <strong>pasteler\u00eda y panader\u00eda<\/strong> que son compatibles con bandejas de <strong>60 x 40 cm<\/strong>, ocasionalmente de 60 x 80 cm. La capacidad tambi\u00e9n es muy importante: los m\u00e1s peque\u00f1os bajobarra son de poco m\u00e1s de 100 L y los m\u00e1s grandes de 6 puertas llegan a los <strong>1600 L<\/strong>.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-81efb78 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"81efb78\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-13aa7ca\" data-id=\"13aa7ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2e04e6 elementor-widget elementor-widget-text-editor\" data-id=\"e2e04e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Los <strong>armarios<\/strong> espec\u00edficos para <strong>farmacia<\/strong> disponen generalmente de niveles de carga deslizantes, son los estantes especiales para acceder m\u00e1s f\u00e1cilmente a los productos almacenados; disponen de alarma en caso de alta temperatura; algunos disponen de <strong>sistema de registro de datos<\/strong> en tarjeta SD para acreditar la unformidad y continuidad de la temperatura, y en general los que tienen la puerta de cristal disponen de <strong>luz LED<\/strong> interior. Los <strong>armarios de fermentaci\u00f3n controlada<\/strong> tienen un amplio rango de temperatura de trabajo: desde -18\u00baC a + 35\u00baC. Son, en definitiva, una fermentadora y un armario de conservaci\u00f3n y congelaci\u00f3n en una sola m\u00e1quina. Es una herramienta muy \u00fatil para <strong>panaderos y pasteleros<\/strong>, ya que te permite introducir la masa, fermentarla y que leve, en un mismo ciclo enfriarla y dejar el armario en modo conservaci\u00f3n, o bien seguir bajando la temperatura y llegar a la congelaci\u00f3n. Todo ello <strong>estandariza la producci\u00f3n<\/strong>, y al ser programable y disponer de extracci\u00f3n de <strong>datos HACCP<\/strong>, cumple con todas las normativas alimentarias. Los <strong>armarios de maduraci\u00f3n de carne<\/strong>, tambi\u00e9n conocidos como <strong>Dry Aging<\/strong>, han empezado a conocerse recientemente y son ideales para locales de restauraci\u00f3n o venta de carne, por el tratamiento que dan al producto. Cuando se lleva a cabo el sacrificio del animal, debido a la falta de agua y ox\u00edgeno circulando, se produce una liberaci\u00f3n masiva de calcio que convierte la carne en incomible, porque estar\u00eda demasiado dura. A partir de ese momento, empieza el <strong>proceso de maduraci\u00f3n<\/strong>, que es el \u201cdry age\u201d \u2013maduraci\u00f3n en seco-. En esta misma l\u00ednea encontramos los <strong>armarios secaderos de embutidos<\/strong>, el proceso viene a ser similar, que aunque no requiere tanta precisi\u00f3n como el Dry Aging, disponen tambi\u00e9n de <strong>control electr\u00f3nico de temperatura y humedad<\/strong>, y el ciclo de secado se produce de forma discontinua.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c4037f6 imatge-fons\" data-id=\"c4037f6\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-afa03af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"afa03af\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06206f3\" data-id=\"06206f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16fa8a4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"16fa8a4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Cuando vayas a <strong>comprar<\/strong> un <strong>armario de refrigeraci\u00f3n industrial<\/strong> debes tener en cuenta la temperatura de trabajo, a qu\u00e9 lo vas a destinar, asegurarte de los accesos y que donde lo coloques tenga una <strong>buena circulaci\u00f3n de aire<\/strong> para que no se sobrecaliente. Igualmente, hay que mantenerlo<strong> limpio<\/strong> y no sobrecargarlo para que el aire circule adecuadamente por el interior. Si tienes cualquier duda a la hora de escoger el armario que m\u00e1s se adapte a tus necesidades, no dudes en <a href=\"https:\/\/www.tophosteleriaprojects.com\/contacto\/\"><strong>consultarnos<\/strong><\/a>.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d48695 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d48695\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-542abb6\" data-id=\"542abb6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-89d4be1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"89d4be1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1a423e7\" data-id=\"1a423e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bb3d2b elementor-widget elementor-widget-heading\" data-id=\"5bb3d2b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ALGUNOS PRODUCTOS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c468f4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0c468f4\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b5e78b4 productes elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b5e78b4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ac5204e\" data-id=\"ac5204e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff2cf7d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ff2cf7d\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-widget-image-box .elementor-image-box-content{width:100%}@media (min-width:768px){.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper,.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{display:flex}.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{text-align:right;flex-direction:row-reverse}.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper{text-align:left;flex-direction:row}.elementor-widget-image-box.elementor-position-top .elementor-image-box-img{margin:auto}.elementor-widget-image-box.elementor-vertical-align-top .elementor-image-box-wrapper{align-items:flex-start}.elementor-widget-image-box.elementor-vertical-align-middle .elementor-image-box-wrapper{align-items:center}.elementor-widget-image-box.elementor-vertical-align-bottom .elementor-image-box-wrapper{align-items:flex-end}}@media (max-width:767px){.elementor-widget-image-box .elementor-image-box-img{margin-left:auto!important;margin-right:auto!important;margin-bottom:15px}}.elementor-widget-image-box .elementor-image-box-img{display:inline-block}.elementor-widget-image-box .elementor-image-box-title a{color:inherit}.elementor-widget-image-box .elementor-image-box-wrapper{text-align:center}.elementor-widget-image-box .elementor-image-box-description{margin:0}<\/style><div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.tophosteleria.com\/es\/serie-60-x-40\/2486-armario-de-refrigeracion-pasteleria-infrico-serie-agb-1400-l-agb-1402-past.html\" tabindex=\"-1\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" loading=\"lazy\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-conservacion-o-congelacion-pasteleria-2-PUERTAS-infrico-serie-AGB-1400-PAST.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1401\" alt=\"\" srcset=\"https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-conservacion-o-congelacion-pasteleria-2-PUERTAS-infrico-serie-AGB-1400-PAST.jpg 1000w, https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-conservacion-o-congelacion-pasteleria-2-PUERTAS-infrico-serie-AGB-1400-PAST-300x300.jpg 300w, https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-conservacion-o-congelacion-pasteleria-2-PUERTAS-infrico-serie-AGB-1400-PAST-150x150.jpg 150w, https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-conservacion-o-congelacion-pasteleria-2-PUERTAS-infrico-serie-AGB-1400-PAST-768x768.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.tophosteleria.com\/es\/serie-60-x-40\/2486-armario-de-refrigeracion-pasteleria-infrico-serie-agb-1400-l-agb-1402-past.html\" target=\"_blank\" rel=\"noopener\">ARMARIO DE REFRIGERACI\u00d3N PASTELER\u00cdA INFRICO SERIE AGB 1400 L \u2013 AGB 1402 PAST<\/a><\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-362e04b\" data-id=\"362e04b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-786a447 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"786a447\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.tophosteleria.com\/es\/maduradores-de-carne\/2713-armario-madurador-de-carne-dry-aging-ddav-200.html\" tabindex=\"-1\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" loading=\"lazy\" width=\"1174\" height=\"1345\" src=\"https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-madurador-de-carne-dry-aging-docriluc-modelo-DDAV-200.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1406\" alt=\"\" srcset=\"https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-madurador-de-carne-dry-aging-docriluc-modelo-DDAV-200.jpg 1174w, https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-madurador-de-carne-dry-aging-docriluc-modelo-DDAV-200-262x300.jpg 262w, https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-madurador-de-carne-dry-aging-docriluc-modelo-DDAV-200-894x1024.jpg 894w, https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-madurador-de-carne-dry-aging-docriluc-modelo-DDAV-200-768x880.jpg 768w\" sizes=\"(max-width: 1174px) 100vw, 1174px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.tophosteleria.com\/es\/maduradores-de-carne\/2713-armario-madurador-de-carne-dry-aging-ddav-200.html\" target=\"_blank\" rel=\"noopener\">ARMARIO MADURADOR DE CARNE DRY AGING DDAV-200<\/a><\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-67f0d7c\" data-id=\"67f0d7c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d83e32c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d83e32c\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.tophosteleria.com\/es\/serie-snack-o-nacional\/2449-armario-expositor-de-congelacion-2-puertas-infrico-nacional-1000-l-an-1000-bt-cr.html\" tabindex=\"-1\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" loading=\"lazy\" width=\"805\" height=\"1000\" src=\"https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-expositor-2-puertas-infrico-serie-nacional-snack.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1414\" alt=\"\" srcset=\"https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-expositor-2-puertas-infrico-serie-nacional-snack.jpg 805w, https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-expositor-2-puertas-infrico-serie-nacional-snack-242x300.jpg 242w, https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-expositor-2-puertas-infrico-serie-nacional-snack-768x954.jpg 768w\" sizes=\"(max-width: 805px) 100vw, 805px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.tophosteleria.com\/es\/serie-snack-o-nacional\/2449-armario-expositor-de-congelacion-2-puertas-infrico-nacional-1000-l-an-1000-bt-cr.html\" target=\"_blank\" rel=\"noopener\">ARMARIO EXPOSITOR DE CONGELACI\u00d3N 2 PUERTAS INFRICO NACIONAL 1000 L \u2013 AN 1000 BT CR<\/a><\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7afdc20\" data-id=\"7afdc20\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6985f7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a6985f7\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.tophosteleria.com\/es\/serie-snack-o-nacional\/2452-armario-de-refrigeracion-5-puertas-infrico-nacional-1600-l-an-1605-tf.html\" tabindex=\"-1\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" loading=\"lazy\" width=\"998\" height=\"994\" src=\"https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-6-puertas-conservacion-serie-nacional-infrico-serie-nacional-1000-L.jpg\" class=\"elementor-animation-grow attachment-full size-full wp-image-1416\" alt=\"\" srcset=\"https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-6-puertas-conservacion-serie-nacional-infrico-serie-nacional-1000-L.jpg 998w, https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-6-puertas-conservacion-serie-nacional-infrico-serie-nacional-1000-L-300x300.jpg 300w, https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-6-puertas-conservacion-serie-nacional-infrico-serie-nacional-1000-L-150x150.jpg 150w, https:\/\/www.tophosteleriaprojects.com\/wp-content\/uploads\/2023\/10\/armario-6-puertas-conservacion-serie-nacional-infrico-serie-nacional-1000-L-768x765.jpg 768w\" sizes=\"(max-width: 998px) 100vw, 998px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.tophosteleria.com\/es\/serie-snack-o-nacional\/2452-armario-de-refrigeracion-5-puertas-infrico-nacional-1600-l-an-1605-tf.html\" target=\"_blank\" rel=\"noopener\">ARMARIO DE REFRIGERACI\u00d3N 6 PUERTAS INFRICO NACIONAL 1600 L \u2013 AN 1606 T\/F<\/a><\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b809143 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b809143\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0bf697d\" data-id=\"0bf697d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44188fe elementor-align-center elementor-widget elementor-widget-button\" data-id=\"44188fe\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.tophosteleria.com\/es\/22-armarios-refrigerados\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-external-link-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver todos<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-947d2e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"947d2e3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20c0a17\" data-id=\"20c0a17\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d09745f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d09745f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6c74756\" data-id=\"6c74756\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d09796a\" data-id=\"d09796a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ARMARIOS Y EXPOSITORES REFRIGERADOS Para acertar en la elecci\u00f3n de un armario refrigerado o un expositor, primero de todo piensa para qu\u00e9 lo necesitas, en base a eso, podr\u00e1s eliminar muchas opciones que no encajar\u00edan en tus necesidades. Debes tener en cuenta el rango de temperatura (conservaci\u00f3n o congelaci\u00f3n), tipo de bandejas; n\u00famero de bandejas&hellip;&nbsp;<a href=\"https:\/\/www.tophosteleriaprojects.com\/es\/maquinaria-frio\/armarios-refrigerados\/\" class=\"\" rel=\"bookmark\">Leer m\u00e1s &raquo;<span class=\"screen-reader-text\">Armarios y expositores<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":656,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","footnotes":""},"_links":{"self":[{"href":"https:\/\/www.tophosteleriaprojects.com\/es\/wp-json\/wp\/v2\/pages\/1135"}],"collection":[{"href":"https:\/\/www.tophosteleriaprojects.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tophosteleriaprojects.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tophosteleriaprojects.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tophosteleriaprojects.com\/es\/wp-json\/wp\/v2\/comments?post=1135"}],"version-history":[{"count":41,"href":"https:\/\/www.tophosteleriaprojects.com\/es\/wp-json\/wp\/v2\/pages\/1135\/revisions"}],"predecessor-version":[{"id":2139,"href":"https:\/\/www.tophosteleriaprojects.com\/es\/wp-json\/wp\/v2\/pages\/1135\/revisions\/2139"}],"up":[{"embeddable":true,"href":"https:\/\/www.tophosteleriaprojects.com\/es\/wp-json\/wp\/v2\/pages\/656"}],"wp:attachment":[{"href":"https:\/\/www.tophosteleriaprojects.com\/es\/wp-json\/wp\/v2\/media?parent=1135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}